{"id":14,"date":"2021-06-18T07:53:21","date_gmt":"2021-06-18T07:53:21","guid":{"rendered":"http:\/\/www.mosleytechnology.com\/?page_id=14"},"modified":"2021-06-26T08:12:12","modified_gmt":"2021-06-26T08:12:12","slug":"blog","status":"publish","type":"page","link":"https:\/\/mosleytechnology.com\/tl\/blog\/","title":{"rendered":"Blog"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"blog.php","meta":{"footnotes":""},"class_list":["post-14","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/mosleytechnology.com\/tl\/blog\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Mosley Technology - technology\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Blog - Mosley Technology\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/mosleytechnology.com\/tl\/blog\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.mosleytechnology.com\/wp-content\/uploads\/2021\/06\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.mosleytechnology.com\/wp-content\/uploads\/2021\/06\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-06-18T07:53:21+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-06-26T08:12:12+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Blog - Mosley Technology\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.mosleytechnology.com\/wp-content\/uploads\/2021\/06\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mosleytechnology.com\\\/tl\\\/blog\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mosleytechnology.com\\\/tl#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mosleytechnology.com\\\/tl\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mosleytechnology.com\\\/tl\\\/blog\\\/#listItem\",\"name\":\"Blog\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mosleytechnology.com\\\/tl\\\/blog\\\/#listItem\",\"position\":2,\"name\":\"Blog\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mosleytechnology.com\\\/tl#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mosleytechnology.com\\\/tl\\\/#organization\",\"name\":\"Mosley Technology\",\"description\":\"technology\",\"url\":\"https:\\\/\\\/mosleytechnology.com\\\/tl\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mosleytechnology.com\\\/tl\\\/blog\\\/#webpage\",\"url\":\"https:\\\/\\\/mosleytechnology.com\\\/tl\\\/blog\\\/\",\"name\":\"Blog - Mosley Technology\",\"inLanguage\":\"tl\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mosleytechnology.com\\\/tl\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mosleytechnology.com\\\/tl\\\/blog\\\/#breadcrumblist\"},\"datePublished\":\"2021-06-18T07:53:21-04:00\",\"dateModified\":\"2021-06-26T08:12:12-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mosleytechnology.com\\\/tl\\\/#website\",\"url\":\"https:\\\/\\\/mosleytechnology.com\\\/tl\\\/\",\"name\":\"Mosley Technology\",\"description\":\"technology\",\"inLanguage\":\"tl\",\"publisher\":{\"@id\":\"https:\\\/\\\/mosleytechnology.com\\\/tl\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Blog - Mosley Technology","description":"","canonical_url":"https:\/\/mosleytechnology.com\/tl\/blog\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/mosleytechnology.com\/tl\/blog\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/mosleytechnology.com\/tl#listItem","position":1,"name":"Home","item":"https:\/\/mosleytechnology.com\/tl","nextItem":{"@type":"ListItem","@id":"https:\/\/mosleytechnology.com\/tl\/blog\/#listItem","name":"Blog"}},{"@type":"ListItem","@id":"https:\/\/mosleytechnology.com\/tl\/blog\/#listItem","position":2,"name":"Blog","previousItem":{"@type":"ListItem","@id":"https:\/\/mosleytechnology.com\/tl#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/mosleytechnology.com\/tl\/#organization","name":"Mosley Technology","description":"technology","url":"https:\/\/mosleytechnology.com\/tl\/"},{"@type":"WebPage","@id":"https:\/\/mosleytechnology.com\/tl\/blog\/#webpage","url":"https:\/\/mosleytechnology.com\/tl\/blog\/","name":"Blog - Mosley Technology","inLanguage":"tl","isPartOf":{"@id":"https:\/\/mosleytechnology.com\/tl\/#website"},"breadcrumb":{"@id":"https:\/\/mosleytechnology.com\/tl\/blog\/#breadcrumblist"},"datePublished":"2021-06-18T07:53:21-04:00","dateModified":"2021-06-26T08:12:12-04:00"},{"@type":"WebSite","@id":"https:\/\/mosleytechnology.com\/tl\/#website","url":"https:\/\/mosleytechnology.com\/tl\/","name":"Mosley Technology","description":"technology","inLanguage":"tl","publisher":{"@id":"https:\/\/mosleytechnology.com\/tl\/#organization"}}]},"og:locale":"en_US","og:site_name":"Mosley Technology - technology","og:type":"article","og:title":"Blog - Mosley Technology","og:url":"https:\/\/mosleytechnology.com\/tl\/blog\/","og:image":"https:\/\/www.mosleytechnology.com\/wp-content\/uploads\/2021\/06\/logo.png","og:image:secure_url":"https:\/\/www.mosleytechnology.com\/wp-content\/uploads\/2021\/06\/logo.png","article:published_time":"2021-06-18T07:53:21+00:00","article:modified_time":"2021-06-26T08:12:12+00:00","twitter:card":"summary","twitter:title":"Blog - Mosley Technology","twitter:image":"https:\/\/www.mosleytechnology.com\/wp-content\/uploads\/2021\/06\/logo.png"},"aioseo_meta_data":{"post_id":"14","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-08-25 10:39:09","updated":"2025-06-03 22:18:57","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/mosleytechnology.com\/tl\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tBlog\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/mosleytechnology.com\/tl"},{"label":"Blog","link":"https:\/\/mosleytechnology.com\/tl\/blog\/"}],"_links":{"self":[{"href":"https:\/\/mosleytechnology.com\/tl\/wp-json\/wp\/v2\/pages\/14","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mosleytechnology.com\/tl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mosleytechnology.com\/tl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mosleytechnology.com\/tl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mosleytechnology.com\/tl\/wp-json\/wp\/v2\/comments?post=14"}],"version-history":[{"count":2,"href":"https:\/\/mosleytechnology.com\/tl\/wp-json\/wp\/v2\/pages\/14\/revisions"}],"predecessor-version":[{"id":31,"href":"https:\/\/mosleytechnology.com\/tl\/wp-json\/wp\/v2\/pages\/14\/revisions\/31"}],"wp:attachment":[{"href":"https:\/\/mosleytechnology.com\/tl\/wp-json\/wp\/v2\/media?parent=14"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}