{"id":15,"date":"2021-06-18T07:53:21","date_gmt":"2021-06-18T07:53:21","guid":{"rendered":"http:\/\/www.mosleytechnology.com\/?page_id=15"},"modified":"2023-05-10T23:13:21","modified_gmt":"2023-05-11T03:13:21","slug":"contact-us","status":"publish","type":"page","link":"https:\/\/mosleytechnology.com\/ur\/contact-us\/","title":{"rendered":"Contact us"},"content":{"rendered":"<div class=\"row\">\n<div class=\"col-md-6\">\n<div class=\"left-side cont_t_one\">\n<h2>Contact Us<\/h2>\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f125-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"125\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/ur\/wp-json\/wp\/v2\/pages\/15#wpcf7-f125-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/ur\/wp-json\/wp\/v2\/pages\/15#wpcf7-f125-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"125\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f125-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"uname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Name\" value=\"\" type=\"text\" name=\"uname\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"uphone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone\" value=\"\" type=\"text\" name=\"uphone\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"uemail\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email\" value=\"\" type=\"email\" name=\"uemail\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"umessage\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Message\" name=\"umessage\"><\/textarea><\/span><br \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Send\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"ur\"\/><\/form>\n<\/div>\n\n<\/div>\n<\/div>\n<div class=\"col-md-6\">\n<section id=\"text-2\" style=\"margin-top: 25px;\">\n<div class=\"right-side\">\n<h2>Get in touch<\/h2>\n<\/div>\n<p><!--\n\n\n<div class=\"add-cont\">\n\n&nbsp;\n\nPhone :<a href=\"tel: 40 4449 6713\">40 4449 6713<\/a>,<a href=\"tel: 67 8596 2764\">67 8596 2764<\/a>\n\n<\/div>\n\n\n--><\/p>\n<\/section>\n<\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"col-md-12\">\n<div class=\"g-map-mosley\"><iframe style=\"border: 0;\" src=\"http:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d212270.0340982516!2d-84.56069071330123!3d33.767919195856926!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x88f5045d6993098d%3A0x66fede2f990b630b!2sAtlanta%2C%20GA%2C%20USA!5e0!3m2!1sen!2sin!4v1628837644058!5m2!1sen!2sin\" width=\"600\" height=\"450\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Contact Us Get in touch<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-15","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Contact Us Get in touch\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/mosleytechnology.com\/ur\/contact-us\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Mosley Technology - technology\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Contact us - Mosley Technology\" \/>\n\t\t<meta property=\"og:description\" content=\"Contact Us Get in touch\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/mosleytechnology.com\/ur\/contact-us\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.mosleytechnology.com\/wp-content\/uploads\/2021\/06\/logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.mosleytechnology.com\/wp-content\/uploads\/2021\/06\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-06-18T07:53:21+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-05-11T03:13:21+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Contact us - Mosley Technology\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Contact Us Get in touch\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.mosleytechnology.com\/wp-content\/uploads\/2021\/06\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mosleytechnology.com\\\/ur\\\/contact-us\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mosleytechnology.com\\\/ur#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mosleytechnology.com\\\/ur\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mosleytechnology.com\\\/ur\\\/contact-us\\\/#listItem\",\"name\":\"Contact us\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mosleytechnology.com\\\/ur\\\/contact-us\\\/#listItem\",\"position\":2,\"name\":\"Contact us\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mosleytechnology.com\\\/ur#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mosleytechnology.com\\\/ur\\\/#organization\",\"name\":\"Mosley Technology\",\"description\":\"technology\",\"url\":\"https:\\\/\\\/mosleytechnology.com\\\/ur\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mosleytechnology.com\\\/ur\\\/contact-us\\\/#webpage\",\"url\":\"https:\\\/\\\/mosleytechnology.com\\\/ur\\\/contact-us\\\/\",\"name\":\"Contact us - Mosley Technology\",\"description\":\"Contact Us Get in touch\",\"inLanguage\":\"ur\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mosleytechnology.com\\\/ur\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mosleytechnology.com\\\/ur\\\/contact-us\\\/#breadcrumblist\"},\"datePublished\":\"2021-06-18T07:53:21-04:00\",\"dateModified\":\"2023-05-10T23:13:21-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mosleytechnology.com\\\/ur\\\/#website\",\"url\":\"https:\\\/\\\/mosleytechnology.com\\\/ur\\\/\",\"name\":\"Mosley Technology\",\"description\":\"technology\",\"inLanguage\":\"ur\",\"publisher\":{\"@id\":\"https:\\\/\\\/mosleytechnology.com\\\/ur\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Contact us - Mosley Technology","description":"Contact Us Get in touch","canonical_url":"https:\/\/mosleytechnology.com\/ur\/contact-us\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/mosleytechnology.com\/ur\/contact-us\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/mosleytechnology.com\/ur#listItem","position":1,"name":"Home","item":"https:\/\/mosleytechnology.com\/ur","nextItem":{"@type":"ListItem","@id":"https:\/\/mosleytechnology.com\/ur\/contact-us\/#listItem","name":"Contact us"}},{"@type":"ListItem","@id":"https:\/\/mosleytechnology.com\/ur\/contact-us\/#listItem","position":2,"name":"Contact us","previousItem":{"@type":"ListItem","@id":"https:\/\/mosleytechnology.com\/ur#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/mosleytechnology.com\/ur\/#organization","name":"Mosley Technology","description":"technology","url":"https:\/\/mosleytechnology.com\/ur\/"},{"@type":"WebPage","@id":"https:\/\/mosleytechnology.com\/ur\/contact-us\/#webpage","url":"https:\/\/mosleytechnology.com\/ur\/contact-us\/","name":"Contact us - Mosley Technology","description":"Contact Us Get in touch","inLanguage":"ur","isPartOf":{"@id":"https:\/\/mosleytechnology.com\/ur\/#website"},"breadcrumb":{"@id":"https:\/\/mosleytechnology.com\/ur\/contact-us\/#breadcrumblist"},"datePublished":"2021-06-18T07:53:21-04:00","dateModified":"2023-05-10T23:13:21-04:00"},{"@type":"WebSite","@id":"https:\/\/mosleytechnology.com\/ur\/#website","url":"https:\/\/mosleytechnology.com\/ur\/","name":"Mosley Technology","description":"technology","inLanguage":"ur","publisher":{"@id":"https:\/\/mosleytechnology.com\/ur\/#organization"}}]},"og:locale":"en_US","og:site_name":"Mosley Technology - technology","og:type":"article","og:title":"Contact us - Mosley Technology","og:description":"Contact Us Get in touch","og:url":"https:\/\/mosleytechnology.com\/ur\/contact-us\/","og:image":"https:\/\/www.mosleytechnology.com\/wp-content\/uploads\/2021\/06\/logo.png","og:image:secure_url":"https:\/\/www.mosleytechnology.com\/wp-content\/uploads\/2021\/06\/logo.png","article:published_time":"2021-06-18T07:53:21+00:00","article:modified_time":"2023-05-11T03:13:21+00:00","twitter:card":"summary","twitter:title":"Contact us - Mosley Technology","twitter:description":"Contact Us Get in touch","twitter:image":"https:\/\/www.mosleytechnology.com\/wp-content\/uploads\/2021\/06\/logo.png"},"aioseo_meta_data":{"post_id":"15","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-08-25 10:39:09","updated":"2025-06-03 22:18:57","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/mosleytechnology.com\/ur\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tContact us\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/mosleytechnology.com\/ur"},{"label":"Contact us","link":"https:\/\/mosleytechnology.com\/ur\/contact-us\/"}],"_links":{"self":[{"href":"https:\/\/mosleytechnology.com\/ur\/wp-json\/wp\/v2\/pages\/15","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mosleytechnology.com\/ur\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mosleytechnology.com\/ur\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mosleytechnology.com\/ur\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mosleytechnology.com\/ur\/wp-json\/wp\/v2\/comments?post=15"}],"version-history":[{"count":6,"href":"https:\/\/mosleytechnology.com\/ur\/wp-json\/wp\/v2\/pages\/15\/revisions"}],"predecessor-version":[{"id":594,"href":"https:\/\/mosleytechnology.com\/ur\/wp-json\/wp\/v2\/pages\/15\/revisions\/594"}],"wp:attachment":[{"href":"https:\/\/mosleytechnology.com\/ur\/wp-json\/wp\/v2\/media?parent=15"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}